{"id":5238,"date":"2026-01-07T08:05:08","date_gmt":"2026-01-07T07:05:08","guid":{"rendered":"https:\/\/www.gout-region.ch\/le-festin-prend-le-train-2\/"},"modified":"2026-06-18T10:12:43","modified_gmt":"2026-06-18T08:12:43","slug":"festessen","status":"publish","type":"post","link":"https:\/\/www.gout-region.ch\/de\/festessen\/","title":{"rendered":"Das Festessen nimmt den Zug!"},"content":{"rendered":"<p>Am Sonntag 8. M\u00e4rz 2026 ladet Sie das Team von Go\u00fbt &amp; R\u00e9gion ein, zu einer Schlemmerreise ins Val-de-Travers! Steigen Sie ein in den Nostalgiezug, der Sie an den Gestaden des Neuenburgersees vorbei, von Neuch\u00e2tel ins Val-de-Travers f\u00fchrt, begleitet von einem echten  <a href=\"https:\/\/www.gout-region.ch\/de\/festessen\/\" title=\"Read more on Das Festessen nimmt den Zug!\" class=\"more-link\">mehr<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am Sonntag 8. M\u00e4rz 2026 ladet Sie das Team von Go\u00fbt &amp; R\u00e9gion ein, zu einer Schlemmerreise ins Val-de-Travers!<\/p>\n","protected":false},"author":1,"featured_media":5224,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"mc4wp_mailchimp_campaign":[]},"categories":[189,153,167],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.9.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Das Festessen nimmt den Zug! - Val-de-Travers<\/title>\n<meta name=\"description\" content=\"Die Asphaltminen heissen Sie herzlich willkommen zum Neuenburger Festmahl. Reisen Sie von Neuenburg ins Val-de-Travers und lassen Sie sich dabei kulinarisch verw\u00f6hnen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gout-region.ch\/de\/festessen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Das Festessen nimmt den Zug! - Val-de-Travers\" \/>\n<meta property=\"og:description\" content=\"Die Asphaltminen heissen Sie herzlich willkommen zum Neuenburger Festmahl. Reisen Sie von Neuenburg ins Val-de-Travers und lassen Sie sich dabei kulinarisch verw\u00f6hnen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gout-region.ch\/de\/festessen\/\" \/>\n<meta property=\"og:site_name\" content=\"Go\u00fbt &amp; R\u00e9gion | Val-de-Travers\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/goutetregion\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-07T07:05:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-18T08:12:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gout-region.ch\/wp-content\/uploads\/2019\/09\/logo_festin_neuchatelois.png\" \/>\n\t<meta property=\"og:image:width\" content=\"228\" \/>\n\t<meta property=\"og:image:height\" content=\"252\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\">\n\t<meta name=\"twitter:data1\" content=\"4\u00a0Minuten\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.gout-region.ch\/de\/#website\",\"url\":\"https:\/\/www.gout-region.ch\/de\/\",\"name\":\"Go\\u00fbt &amp; R\\u00e9gion | Val-de-Travers\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.gout-region.ch\/de\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.gout-region.ch\/de\/festessen\/#primaryimage\",\"inLanguage\":\"de\",\"url\":\"https:\/\/www.gout-region.ch\/wp-content\/uploads\/2019\/09\/logo_festin_neuchatelois.png\",\"width\":228,\"height\":252,\"caption\":\"Festin neuch\\u00e2telois\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.gout-region.ch\/de\/festessen\/#webpage\",\"url\":\"https:\/\/www.gout-region.ch\/de\/festessen\/\",\"name\":\"Das Festessen nimmt den Zug! - Val-de-Travers\",\"isPartOf\":{\"@id\":\"https:\/\/www.gout-region.ch\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.gout-region.ch\/de\/festessen\/#primaryimage\"},\"datePublished\":\"2026-01-07T07:05:08+00:00\",\"dateModified\":\"2026-06-18T08:12:43+00:00\",\"author\":{\"@id\":\"https:\/\/www.gout-region.ch\/de\/#\/schema\/person\/00e6d034f0dd5ac1ab72f0692b577f0e\"},\"description\":\"Die Asphaltminen heissen Sie herzlich willkommen zum Neuenburger Festmahl. Reisen Sie von Neuenburg ins Val-de-Travers und lassen Sie sich dabei kulinarisch verw\\u00f6hnen!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.gout-region.ch\/de\/festessen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.gout-region.ch\/de\/festessen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.gout-region.ch\/de\/festessen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.gout-region.ch\/de\/\",\"url\":\"https:\/\/www.gout-region.ch\/de\/\",\"name\":\"Accueil\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.gout-region.ch\/de\/festessen\/\",\"url\":\"https:\/\/www.gout-region.ch\/de\/festessen\/\",\"name\":\"Das Festessen nimmt den Zug!\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.gout-region.ch\/de\/#\/schema\/person\/00e6d034f0dd5ac1ab72f0692b577f0e\",\"name\":\"adminGR\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.gout-region.ch\/de\/#personlogo\",\"inLanguage\":\"de\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/21522ab5eb10ea930f78a6dc014f0d12?s=96&d=mm&r=g\",\"caption\":\"adminGR\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.gout-region.ch\/de\/wp-json\/wp\/v2\/posts\/5238"}],"collection":[{"href":"https:\/\/www.gout-region.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gout-region.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gout-region.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gout-region.ch\/de\/wp-json\/wp\/v2\/comments?post=5238"}],"version-history":[{"count":22,"href":"https:\/\/www.gout-region.ch\/de\/wp-json\/wp\/v2\/posts\/5238\/revisions"}],"predecessor-version":[{"id":9286,"href":"https:\/\/www.gout-region.ch\/de\/wp-json\/wp\/v2\/posts\/5238\/revisions\/9286"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gout-region.ch\/de\/wp-json\/wp\/v2\/media\/5224"}],"wp:attachment":[{"href":"https:\/\/www.gout-region.ch\/de\/wp-json\/wp\/v2\/media?parent=5238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gout-region.ch\/de\/wp-json\/wp\/v2\/categories?post=5238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gout-region.ch\/de\/wp-json\/wp\/v2\/tags?post=5238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}